{"id":12724,"date":"2021-12-08T08:07:39","date_gmt":"2021-12-08T08:07:39","guid":{"rendered":"https:\/\/staging.liquid-themes.com\/original\/?page_id=12724"},"modified":"2025-05-15T18:45:44","modified_gmt":"2025-05-15T18:45:44","slug":"clinicaintegrasp","status":"publish","type":"page","link":"https:\/\/spintegrasaude.com.br\/","title":{"rendered":"Cl\u00ednica Integra SP"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"12724\" class=\"elementor elementor-12724\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4377ecb0 elementor-section-height-min-height elementor-section-items-stretch elementor-section-boxed elementor-section-height-default\" data-id=\"4377ecb0\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;shape_divider_bottom&quot;:&quot;lqd-custom-shape-15&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:13202,&quot;url&quot;:&quot;https:\\\/\\\/spintegrasaude.com.br\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/site2.jpg&quot;}],&quot;background_slideshow_ken_burns&quot;:&quot;yes&quot;,&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500,&quot;background_slideshow_ken_burns_zoom_direction&quot;:&quot;in&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" data-negative=\"false\">\n\t\t\t<svg class=\"lqd-custom-shape\"  fill=\"none\" height=\"461\" viewBox=\"0 0 1440 461\" width=\"1440\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" preserveAspectRatio=\"none\">\n  <path class=\"elementor-shape-fill\" d=\"m0 131.906 34.4-20.017c34.4-19.9 103.2-59.936 171.68-82.979 68.64-23.043 136.8-29.328003 205.44-4.306 68.48 25.022 137.28 81.35 205.76 80.768 68.64-.582 136.8-58.074 205.44-84.608 68.48-26.535 137.28-22.345 205.76-16.06 68.64 6.168 136.8 14.315 205.44 22.811 68.48 8.612 137.28 17.457 171.68 22l34.4 4.422v396.851h-1440z\" fill-opacity=\".09\">\n    <animate repeatCount=\"indefinite\" fill=\"freeze\" attributeName=\"d\" dur=\"10s\" values=\"M0 131.906L34.4 111.889C68.8 91.989 137.6 51.953 206.08 28.91C274.72 5.867 342.88 -0.418001 411.52 24.604C480 49.626 548.8 105.954 617.28 105.372C685.92 104.79 754.08 47.298 822.72 20.764C891.2 -5.771 960 -1.581 1028.48 4.704C1097.12 10.872 1165.28 19.019 1233.92 27.515C1302.4 36.127 1371.2 44.972 1405.6 49.515L1440 53.937V450.788H0L0 131.906Z; M0 122.906L36.5 109C71.5 96.372 102.52 67.98 171 44.937C239.64 21.894 354.36 51.478 423 76.5C491.48 101.522 546.52 19.097 615 18.515C683.64 17.933 799.36 58.534 868 32C936.48 5.46499 1039.52 54.715 1108 61C1176.64 67.168 1190.36 -6.996 1259 1.5C1327.48 10.112 1371.2 35.972 1405.6 40.515L1440 44.937V441.788H0L0 122.906Z; M0 131.906L34.4 111.889C68.8 91.989 137.6 51.953 206.08 28.91C274.72 5.867 342.88 -0.418001 411.52 24.604C480 49.626 548.8 105.954 617.28 105.372C685.92 104.79 754.08 47.298 822.72 20.764C891.2 -5.771 960 -1.581 1028.48 4.704C1097.12 10.872 1165.28 19.019 1233.92 27.515C1302.4 36.127 1371.2 44.972 1405.6 49.515L1440 53.937V450.788H0L0 131.906Z\">\n    <\/animate>\n  <\/path>\n  <path class=\"elementor-shape-fill\" d=\"M0 154.75L34.4 142.201C68.8 129.53 137.6 104.433 206.08 99.072C274.72 93.833 342.88 108.453 411.52 122.099C480 135.622 548.8 148.293 617.28 142.811C685.92 137.329 754.08 113.693 822.72 113.693C891.2 113.693 960 137.329 1028.48 152.68C1097.12 168.153 1165.28 175.463 1233.92 184.966C1302.4 194.591 1371.2 206.287 1405.6 212.257L1440 218.105V452.025H0L0 154.75Z\" fill-opacity=\".28\">\n    <animate repeatCount=\"indefinite\" fill=\"freeze\" attributeName=\"d\" dur=\"8s\" values=\"M0 154.75C0 154.75 12.8 142.902 34.4 142.201C56 141.5 140.02 160.111 208.5 154.75C277.14 149.511 334.36 112.57 403 126.216C471.48 139.739 552.52 190.448 621 184.966C689.64 179.484 745.36 116 814 116C882.48 116 950.52 161.149 1019 176.5C1087.64 191.973 1154.36 123.997 1223 133.5C1291.48 143.125 1371.2 206.287 1405.6 212.257L1440 218.105V452.025H0L0 154.75Z; M0 154.75C0 154.75 33.4 177.201 55 176.5C76.6 175.799 137.52 110.361 206 105C274.64 99.761 332.86 141.104 401.5 154.75C469.98 168.273 527.52 206.982 596 201.5C664.64 196.018 747.86 75 816.5 75C884.98 75 956.52 118.149 1025 133.5C1093.64 148.973 1163.36 87.497 1232 97C1300.48 106.625 1371.2 206.287 1405.6 212.257L1440 218.105V452.025H0L0 154.75Z; M0 154.75C0 154.75 12.8 142.902 34.4 142.201C56 141.5 140.02 160.111 208.5 154.75C277.14 149.511 334.36 112.57 403 126.216C471.48 139.739 552.52 190.448 621 184.966C689.64 179.484 745.36 116 814 116C882.48 116 950.52 161.149 1019 176.5C1087.64 191.973 1154.36 123.997 1223 133.5C1291.48 143.125 1371.2 206.287 1405.6 212.257L1440 218.105V452.025H0L0 154.75Z\">\n    <\/animate>\n  <\/path>\n  <path class=\"elementor-shape-fill\" d=\"M0 340.22L34.4 333.92C68.8 327.52 137.6 314.92 206.08 312.22C274.72 309.52 342.88 316.92 411.52 319.72C480 322.52 548.8 320.92 617.28 318.92C685.92 316.92 754.08 314.52 822.72 316.02C891.2 317.52 960 322.92 1028.48 309.42C1097.12 295.92 1165.28 263.52 1233.92 251.02C1302.4 238.52 1371.2 245.92 1405.6 249.52L1440 253.22V453.22H0L0 340.22Z\">\n    <animate repeatCount=\"indefinite\" fill=\"freeze\" attributeName=\"d\" dur=\"6.5s\" values=\"M0 340.22L34.4 333.92C68.8 327.52 139.02 281.2 207.5 278.5C276.14 275.8 351.86 331.12 420.5 333.92C488.98 336.72 554.52 289 623 287C691.64 285 756.86 332.42 825.5 333.92C893.98 335.42 960 322.92 1028.48 309.42C1097.12 295.92 1163.36 236 1232 223.5C1300.48 211 1371.2 245.92 1405.6 249.52L1440 253.22V453.22H0L0 340.22Z; M0 340.22L37.5 323C71.9 316.6 137.52 336.62 206 333.92C274.64 331.22 339.86 272.2 408.5 275C476.98 277.8 551.02 304 619.5 302C688.14 300 759.36 266.5 828 268C896.48 269.5 962.02 336.5 1030.5 323C1099.14 309.5 1156.36 232.5 1225 220C1293.48 207.5 1364.1 249.62 1398.5 253.22L1440 253.22V453.22H0L0 340.22Z; M0 340.22L34.4 333.92C68.8 327.52 139.02 281.2 207.5 278.5C276.14 275.8 351.86 331.12 420.5 333.92C488.98 336.72 554.52 289 623 287C691.64 285 756.86 332.42 825.5 333.92C893.98 335.42 960 322.92 1028.48 309.42C1097.12 295.92 1163.36 236 1232 223.5C1300.48 211 1371.2 245.92 1405.6 249.52L1440 253.22V453.22H0L0 340.22Z\">\n    <\/animate>\n  <\/path>\n  <path class=\"elementor-shape-fill\" d=\"M1440 337.719L1405.6 340.219C1371.2 342.719 1302.4 347.719 1233.92 350.419C1165.28 353.019 1097.12 353.419 1028.48 352.219C960 351.019 891.2 348.419 822.72 357.019C754.08 365.719 685.92 385.719 617.28 395.919C548.8 406.019 480 406.419 411.52 395.919C342.88 385.419 274.72 364.019 206.08 359.419C137.6 354.719 68.8 366.719 34.4 372.719L0 378.719V460.719H1440V337.719Z\">\n    <animate repeatCount=\"indefinite\" fill=\"freeze\" attributeName=\"d\" dur=\"5.5s\" values=\"M1440 337.719L1405.6 340.219C1371.2 342.719 1303.98 362.8 1235.5 365.5C1166.86 368.1 1090.14 324.2 1021.5 323C953.02 321.8 889.48 383.4 821 392C752.36 400.7 678.64 368.519 610 378.719C541.52 388.819 473.48 414.5 405 404C336.36 393.5 273.64 342.319 205 337.719C136.52 333.019 68.8 366.719 34.4 372.719L0 378.719V460.719H1440V337.719Z; M1440 337.719L1405.6 340.219C1371.2 342.719 1295.98 326.3 1227.5 329C1158.86 331.6 1081.64 391.2 1013 390C944.52 388.8 874.48 364.119 806 372.719C737.36 381.419 675.14 296.3 606.5 306.5C538.02 316.6 471.48 383.219 403 372.719C334.36 362.219 272.64 320.6 204 316C135.52 311.3 68.8 366.719 34.4 372.719L0 378.719V460.719H1440V337.719Z; M1440 337.719L1405.6 340.219C1371.2 342.719 1303.98 362.8 1235.5 365.5C1166.86 368.1 1090.14 324.2 1021.5 323C953.02 321.8 889.48 383.4 821 392C752.36 400.7 678.64 368.519 610 378.719C541.52 388.819 473.48 414.5 405 404C336.36 393.5 273.64 342.319 205 337.719C136.52 333.019 68.8 366.719 34.4 372.719L0 378.719V460.719H1440V337.719Z\">\n    <\/animate>\n  <\/path>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div data-parallax=\"true\" data-parallax-options=\"{&quot;ease&quot;:[&quot;linear&quot;],&quot;start&quot;:&quot;top top&quot;,&quot;end&quot;:&quot;bottom+=0px top&quot;}\" data-parallax-from=\"{&quot;y&quot;:&quot;0px&quot;,&quot;opacity&quot;:1}\" data-parallax-to=\"{&quot;y&quot;:&quot;-100px&quot;,&quot;opacity&quot;:0}\" data-custom-animations=\"true\" data-ca-options=\"{&quot;addChildTimelines&quot;:false,&quot;animationTarget&quot;:&quot;:scope &gt; .elementor-widget-wrap &gt; .elementor-element &gt; .elementor-widget-container, :scope &gt; .elementor-widget-wrap &gt; .elementor-section &gt; .elementor-container &gt; .elementor-column &gt; .elementor-widget-wrap &gt; .elementor-element:not(.lqd-el-has-inner-anim) &gt; .elementor-widget-container, :scope &gt; .elementor-widget-wrap &gt; .elementor-widget-hub_fancy_heading .lqd-split-lines .lqd-lines .split-inner, :scope &gt; .elementor-widget-wrap &gt; .elementor-widget-hub_fancy_heading .lqd-split-words .lqd-words .split-inner, :scope &gt; .elementor-widget-wrap &gt; .elementor-widget-hub_fancy_heading .lqd-split-chars .lqd-chars .split-inner, :scope &gt; .elementor-widget-wrap &gt; .elementor-widget-ld_custom_menu .lqd-fancy-menu &gt; ul &gt; li&quot;,&quot;duration&quot;:1000,&quot;delay&quot;:15,&quot;ease&quot;:[&quot;power4.out&quot;],&quot;initValues&quot;:{&quot;y&quot;:&quot;60px&quot;,&quot;opacity&quot;:0,&quot;transformOrigin&quot;:&quot;65% 50% 0px&quot;},&quot;animations&quot;:{&quot;y&quot;:&quot;0px&quot;,&quot;opacity&quot;:1,&quot;transformOrigin&quot;:&quot;50% 50% 0px&quot;}}\" class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-48eec48a\" data-id=\"48eec48a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2105a35 elementor-widget elementor-widget-menu-anchor\" data-id=\"2105a35\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.8.1 - 13-11-2022 *\/\nbody.elementor-page .elementor-widget-menu-anchor{margin-bottom:0}<\/style>\t\t<div id=\"inicio\" class=\"elementor-menu-anchor\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-120ce30 elementor-widget elementor-widget-image\" data-id=\"120ce30\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.8.1 - 13-11-2022 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"780\" height=\"272\" src=\"https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2022\/11\/Integra_Saude_PNG-1024x357.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2022\/11\/Integra_Saude_PNG-1024x357.png 1024w, https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2022\/11\/Integra_Saude_PNG-300x105.png 300w, https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2022\/11\/Integra_Saude_PNG-1536x536.png 1536w, https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2022\/11\/Integra_Saude_PNG-2048x715.png 2048w\" sizes=\"(max-width: 780px) 100vw, 780px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-536b4739 elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"536b4739\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div id=\"ld-fancy-heading-69fc6d6e9feca\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<h5 class=\"ld-fh-element d-inline-block pos-rel  elementor-heading-title lqd-highlight-classic lqd-highlight-grow-left h5\"  > Recupere sua confian\u00e7a e bem-estar! Agende uma avalia\u00e7\u00e3o hoje e d\u00ea o primeiro passo para uma vida sem desconforto e limita\u00e7\u00f5es.\n<\/h5>\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c4801f elementor-widget elementor-widget-ld_button\" data-id=\"6c4801f\" data-element_type=\"widget\" data-widget_type=\"ld_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<a  href=\"https:\/\/api.whatsapp.com\/send?phone=5511998537408&amp;text=Ol%C3%A1%2C%20vim%20atrav%C3%A9s%20do%20site%20e%20gostaria%20de%20ter%20mais%20informa%C3%A7%C3%B5es%20para%20agendar%20uma%20consulta!\" class=\"elementor-button btn ws-nowrap btn-solid btn-hover-txt-liquid-x btn-has-label\" >\n\t\t\t\t\t\t\t<span class=\"btn-txt\"  data-text=\"Agende J\u00e1 pelo Whatsapp!\" data-split-text=\"true\"\n\t\t\t\t\t    data-split-options='{\"type\": \"chars, words\"}'>Agende J\u00e1 pelo Whatsapp!<\/span>\n\t\t\t\t\t\t\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9dbe0a5 elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"9dbe0a5\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div id=\"ld-fancy-heading-69fc6d6ea85ef\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<h5 class=\"ld-fh-element d-inline-block pos-rel  elementor-heading-title lqd-highlight-classic lqd-highlight-grow-left h5\"  > ou ligue para (11) 99853-7408\n<\/h5>\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a8eced6 elementor-widget elementor-widget-ld_button\" data-id=\"4a8eced6\" data-element_type=\"widget\" data-widget_type=\"ld_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<a  href=\"#\" class=\"elementor-button btn ws-nowrap btn-naked btn-icon-block btn-icon-top btn-icon-circle btn-icon-lg btn-icon-shaped btn-icon-solid btn-icon-ripple btn-no-label\" data-localscroll=\"true\" data-localscroll-options=\"{&quot;scrollBelowSection&quot;:true}\" >\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"btn-icon\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"lqd-icn-ess icon-ion-ios-arrow-down\"><\/i>\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9b595d2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9b595d2\" data-element_type=\"section\" id=\"about\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-42f18320\" data-id=\"42f18320\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c225f1e elementor-widget elementor-widget-menu-anchor\" data-id=\"c225f1e\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"servicos\" class=\"elementor-menu-anchor\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2b17de56 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2b17de56\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4708ee78\" data-id=\"4708ee78\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-70ea6ed0 elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"70ea6ed0\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div id=\"ld-fancy-heading-69fc6d6eb3a7a\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<h6 class=\"ld-fh-element d-inline-block pos-rel  elementor-heading-title lqd-highlight-classic lqd-highlight-grow-left h6\"  > Somos especializados em<\/h6>\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e386f07 elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"6e386f07\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div id=\"ld-fancy-heading-69fc6d6eb5b30\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<h2 class=\"ld-fh-element d-inline-block pos-rel  elementor-heading-title lqd-highlight-classic lqd-highlight-grow-left h2\"  > Fisioterapia P\u00e9lvica.<\/h2>\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-21742b17\" data-id=\"21742b17\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-303f8bea elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"303f8bea\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div id=\"ld-fancy-heading-69fc6d6eb85f0\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<p class=\"ld-fh-element d-inline-block pos-rel  lqd-highlight-classic lqd-highlight-grow-left p\"  > Nossa cl\u00ednica est\u00e1 localizada na Vila Mariana em S\u00e3o Paulo, atendemos Homens e Mulheres<\/p>\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5058e4b7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5058e4b7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-4fa1fd04\" data-id=\"4fa1fd04\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5fd74661 elementor-align-left elementor-widget elementor-widget-ld_icon_box\" data-id=\"5fd74661\" data-element_type=\"widget\" data-widget_type=\"ld_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t\t<div id=\"ld_icon_box_5fd74661\" class=\"iconbox d-flex flex-grow-1 pos-rel flex-column iconbox-default\"   >\n\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"iconbox-icon-wrap  \"><div class=\"iconbox-icon-container d-inline-flex   \"><i aria-hidden=\"true\" class=\"lqd-icn-ess icon-lqd-circle\"><\/i><\/div><\/div>\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t<div class=\"contents \">\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t<h3 class=\"lqd-iconbox-heading \" >Obstetr\u00edcia <\/h3>\t\t\t\t<p><span style=\"font-size: 15px\">Nesta \u00e1rea auxiliamos uma gesta\u00e7\u00e3o saud\u00e1vel, com atua\u00e7\u00e3o em eventuais disfun\u00e7\u00f5es deste per\u00edodo como dor, incontin\u00eancias, edema, postura, prepara\u00e7\u00e3o para o pr\u00e9-parto, parto e p\u00f3s parto<\/span><\/p>\n\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-6356716\" data-id=\"6356716\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-428c639 elementor-align-left elementor-widget elementor-widget-ld_icon_box\" data-id=\"428c639\" data-element_type=\"widget\" data-widget_type=\"ld_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t\t<div id=\"ld_icon_box_428c639\" class=\"iconbox d-flex flex-grow-1 pos-rel flex-column iconbox-default\"   >\n\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"iconbox-icon-wrap  \"><div class=\"iconbox-icon-container d-inline-flex   \"><i aria-hidden=\"true\" class=\"lqd-icn-ess icon-lqd-circle\"><\/i><\/div><\/div>\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t<div class=\"contents \">\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t<h3 class=\"lqd-iconbox-heading \" >Uroginecologia <\/h3>\t\t\t\t<p><span style=\"font-size: 15px\">Na Urologia atuamos no tratamento para as disfun\u00e7\u00f5es urin\u00e1rias como incontin\u00eancias e reten\u00e7\u00e3o urin\u00e1ria. \nNa ginecologia tamb\u00e9m atuamos com prolapsos de \u00f3rg\u00e3os p\u00e9lvicos. .<\/span><\/p>\n\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-774f3f66\" data-id=\"774f3f66\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-67d5a01d elementor-align-left elementor-widget elementor-widget-ld_icon_box\" data-id=\"67d5a01d\" data-element_type=\"widget\" data-widget_type=\"ld_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t\t<div id=\"ld_icon_box_67d5a01d\" class=\"iconbox d-flex flex-grow-1 pos-rel flex-column iconbox-default\"   >\n\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"iconbox-icon-wrap  \"><div class=\"iconbox-icon-container d-inline-flex   \"><i aria-hidden=\"true\" class=\"lqd-icn-ess icon-lqd-circle\"><\/i><\/div><\/div>\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t<div class=\"contents \">\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t<h3 class=\"lqd-iconbox-heading \" >Sa\u00fade do Homem <\/h3>\t\t\t\t<p><span style=\"font-size: 15px\">Incontin\u00eancias urin\u00e1rias p\u00f3s prostatectomia radical e cirurgias de pr\u00f3stata em geral. Acompanhamento e tratamento p\u00f3s c\u00e2ncer de bexiga e pr\u00f3stata. <\/span><\/p>\n\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ed97c1d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ed97c1d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3f0c41e\" data-id=\"3f0c41e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dd45801 elementor-align-left elementor-widget elementor-widget-ld_icon_box\" data-id=\"dd45801\" data-element_type=\"widget\" data-widget_type=\"ld_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t\t<div id=\"ld_icon_box_dd45801\" class=\"iconbox d-flex flex-grow-1 pos-rel flex-column iconbox-default\"   >\n\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"iconbox-icon-wrap  \"><div class=\"iconbox-icon-container d-inline-flex   \"><i aria-hidden=\"true\" class=\"lqd-icn-ess icon-lqd-circle\"><\/i><\/div><\/div>\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t<div class=\"contents \">\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t<h3 class=\"lqd-iconbox-heading \" >Sexualidade <\/h3>\t\t\t\t<p><span style=\"font-size: 15px\">Atuamos nas disfun\u00e7\u00f5es sexuais femininas como vaginismo, dispareunia e nas disfun\u00e7\u00f5es sexuais masculinas: Disfun\u00e7\u00e3o er\u00e9til p\u00f3s prostatectomia e ejacula\u00e7\u00e3o precoce. <\/span><\/p>\n\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-47b2b30\" data-id=\"47b2b30\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a695a99 elementor-align-left elementor-widget elementor-widget-ld_icon_box\" data-id=\"a695a99\" data-element_type=\"widget\" data-widget_type=\"ld_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t\t<div id=\"ld_icon_box_a695a99\" class=\"iconbox d-flex flex-grow-1 pos-rel flex-column iconbox-default\"   >\n\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"iconbox-icon-wrap  \"><div class=\"iconbox-icon-container d-inline-flex   \"><i aria-hidden=\"true\" class=\"lqd-icn-ess icon-lqd-circle\"><\/i><\/div><\/div>\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t<div class=\"contents \">\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t<h3 class=\"lqd-iconbox-heading \" >Coloproctologia <\/h3>\t\t\t\t<p><span style=\"font-size: 15px\">Atua\u00e7\u00f5es em disfun\u00e7\u00f5es intestinais: Constipa\u00e7\u00e3o Intestinal, urg\u00eancia e incontin\u00eancia fecal, s\u00edndromes dolorosas anais. \nAcompanhamento e tratamento no pr\u00e9 e p\u00f3s c\u00e2ncer colorretal.<\/span><\/p>\n\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2fa860f9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2fa860f9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-67ceacef\" data-id=\"67ceacef\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-16c3eaaf elementor-widget__width-initial elementor-widget elementor-widget-ld_fancy_image\" data-id=\"16c3eaaf\" data-element_type=\"widget\" data-widget_type=\"ld_fancy_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t\t<div class=\"lqd-imggrp-single d-block pos-rel perspective\" data-shadow-style=\"3\" data-hover3d=\"true\"  >\n\t\t\t\t\n\t\t\t<div class=\"lqd-imggrp-img-container d-inline-flex pos-rel align-items-center justify-content-center transform-style-3d\">\n\t\t\t\t\t\t\t\t<figure class=\"w-100 pos-rel\" data-stacking-factor=\"1\"  >\n\t\t\t\t\t<img width=\"1083\" height=\"982\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 1083 982&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"Cl\u00ednica Integra SP\" decoding=\"async\" itemprop=\"image\" data-src=\"https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2022\/11\/Site.jpg\" data-srcset=\"https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2022\/11\/Site.jpg 1083w, https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2022\/11\/Site-300x272.jpg 300w, https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2022\/11\/Site-1024x929.jpg 1024w\" data-sizes=\"(max-width: 1083px) 100vw, 1083px\" data-aspect=\"1.1028513238289\" \/>\t\t\t\t\t<span class=\"lqd-overlay lqd-imggrp-overlay-bg\"><\/span>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3ebe5f5d\" data-id=\"3ebe5f5d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-17e82c42 elementor-widget__width-auto elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"17e82c42\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div id=\"ld-fancy-heading-69fc6d6ef0e0a\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<h6 class=\"ld-fh-element d-inline-block pos-rel  elementor-heading-title lqd-highlight-classic lqd-highlight-grow-left h6\"  > SOBRE A CL\u00cdNICA<\/h6>\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1887b554 elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"1887b554\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div id=\"ld-fancy-heading-69fc6d6ef2244\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<h2 class=\"ld-fh-element d-inline-block pos-rel  elementor-heading-title lqd-highlight-classic lqd-highlight-grow-left h2\"  > Qualidade e resultado que voc\u00ea precisa<\/h2>\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c72f6b elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"1c72f6b\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div id=\"ld-fancy-heading-69fc6d6ef3b6a\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<p class=\"ld-fh-element d-inline-block pos-rel  lqd-highlight-classic lqd-highlight-grow-left p\"  > Somos duas fisioterapeutas p\u00e9lvicas que nos unimos para criar um servi\u00e7o de qualidade que acolha o paciente em seu todo.\n<Br><Br>Pensando desta forma, disponibilizamos al\u00e9m dos servi\u00e7os de fisioterapia p\u00e9lvica a \u00e1rea da nutri\u00e7\u00e3o e da massoterapia no mesmo espa\u00e7o.<\/p>\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a09125 elementor-widget elementor-widget-ld_button\" data-id=\"7a09125\" data-element_type=\"widget\" data-widget_type=\"ld_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<a  href=\"https:\/\/api.whatsapp.com\/send?phone=5511998537408&amp;text=Ol%C3%A1%2C%20vim%20atrav%C3%A9s%20do%20site%20e%20gostaria%20de%20ter%20mais%20informa%C3%A7%C3%B5es%20para%20agendar%20uma%20consulta!\" class=\"elementor-button btn ws-nowrap btn-solid btn-hover-txt-liquid-x btn-has-label\" >\n\t\t\t\t\t\t\t<span class=\"btn-txt\"  data-text=\"Agendar uma consulta!\" data-split-text=\"true\"\n\t\t\t\t\t    data-split-options='{\"type\": \"chars, words\"}'>Agendar uma consulta!<\/span>\n\t\t\t\t\t\t\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-40e49fa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"40e49fa\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9aa326b\" data-id=\"9aa326b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2cd81b7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2cd81b7\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7b289a4\" data-id=\"7b289a4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2376b33 elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"2376b33\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div id=\"ld-fancy-heading-69fc6d6f0538d\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<h2 class=\"ld-fh-element d-inline-block pos-rel  elementor-heading-title lqd-highlight-classic lqd-highlight-grow-left h2\"  > Voc\u00ea sofre de alguns desses problemas?<\/h2>\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8972a4c elementor-mobile-align-center elementor-widget elementor-widget-ld_button\" data-id=\"8972a4c\" data-element_type=\"widget\" data-widget_type=\"ld_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<a  href=\"https:\/\/api.whatsapp.com\/send?phone=5511998537408&amp;text=Ol%C3%A1%2C%20vim%20atrav%C3%A9s%20do%20site%20e%20gostaria%20de%20ter%20mais%20informa%C3%A7%C3%B5es%20para%20agendar%20uma%20consulta!\" class=\"elementor-button btn ws-nowrap btn-solid btn-hover-txt-liquid-x btn-block btn-has-label\" >\n\t\t\t\t\t\t\t<span class=\"btn-txt\"  data-text=\"Agendar uma consulta!\" data-split-text=\"true\"\n\t\t\t\t\t    data-split-options='{\"type\": \"chars, words\"}'>Agendar uma consulta!<\/span>\n\t\t\t\t\t\t\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-c0a104c\" data-id=\"c0a104c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c371b96 elementor-widget elementor-widget-ld_list\" data-id=\"c371b96\" data-element_type=\"widget\" data-widget_type=\"ld_list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"lqd-bullet-list\">\n\n\t\t\t<ul class=\"bullet-list-ul reset-ul\">\n\t\t\t\t\t\t\t\t\t\t<li class=\"d-flex align-items-center\"> Incontin\u00eancia urin\u00e1ria feminina<\/li>\n\t\t\t\t\t\t\t\t\t\t<li class=\"d-flex align-items-center\">Incontin\u00eancia urin\u00e1ria masculina<\/li>\n\t\t\t\t\t\t\t\t\t\t<li class=\"d-flex align-items-center\">Constipa\u00e7\u00e3o Intestinal<\/li>\n\t\t\t\t\t\t\t\t\t\t<li class=\"d-flex align-items-center\">Anismo<\/li>\n\t\t\t\t\t\t\t\t\t\t<li class=\"d-flex align-items-center\">Incontin\u00eancia Fecal<\/li>\n\t\t\t\t\t\t\t<\/ul>\n\n\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-481869f\" data-id=\"481869f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-05ed153 elementor-widget elementor-widget-ld_list\" data-id=\"05ed153\" data-element_type=\"widget\" data-widget_type=\"ld_list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"lqd-bullet-list\">\n\n\t\t\t<ul class=\"bullet-list-ul reset-ul\">\n\t\t\t\t\t\t\t\t\t\t<li class=\"d-flex align-items-center\">Reten\u00e7\u00e3o miccional<\/li>\n\t\t\t\t\t\t\t\t\t\t<li class=\"d-flex align-items-center\">Dificuldade de esvaziamento urin\u00e1rio e fecal<\/li>\n\t\t\t\t\t\t\t\t\t\t<li class=\"d-flex align-items-center\">Dor P\u00e9lvica Cr\u00f4nica<\/li>\n\t\t\t\t\t\t\t\t\t\t<li class=\"d-flex align-items-center\">Prolapsos<\/li>\n\t\t\t\t\t\t\t\t\t\t<li class=\"d-flex align-items-center\">Disfun\u00e7\u00e3o Er\u00e9til<\/li>\n\t\t\t\t\t\t\t\t\t\t<li class=\"d-flex align-items-center\">Disfun\u00e7\u00e3o sexual feminina<\/li>\n\t\t\t\t\t\t\t<\/ul>\n\n\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4d3f2783 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4d3f2783\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_top&quot;:&quot;lqd-custom-shape-1&quot;,&quot;shape_divider_bottom&quot;:&quot;lqd-custom-shape-1&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" data-negative=\"false\">\n\t\t\t<svg class=\"lqd-custom-shape\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1943 98.812\" preserveAspectRatio=\"none\">\n    <path class=\"elementor-shape-fill\" d=\"M0,0Q199.075,74.109,485.75,74.109C806.262,74.109,1214.291,0,1578.6,0H1943V98.812H0\" \/>\n<\/svg>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" data-negative=\"false\">\n\t\t\t<svg class=\"lqd-custom-shape\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1943 98.812\" preserveAspectRatio=\"none\">\n    <path class=\"elementor-shape-fill\" d=\"M0,0Q199.075,74.109,485.75,74.109C806.262,74.109,1214.291,0,1578.6,0H1943V98.812H0\" \/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7fb50bb1\" data-id=\"7fb50bb1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-51865d5 elementor-widget__width-auto elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"51865d5\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div id=\"ld-fancy-heading-69fc6d6f0dd3c\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<h6 class=\"ld-fh-element d-inline-block pos-rel  elementor-heading-title lqd-highlight-classic lqd-highlight-grow-left h6\"  > DEPOIMENTOS<\/h6>\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a0c21dd elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"3a0c21dd\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div id=\"ld-fancy-heading-69fc6d6f0f30d\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<h2 class=\"ld-fh-element d-inline-block pos-rel  elementor-heading-title lqd-highlight-classic lqd-highlight-grow-left h2\"  > Resultados<\/h2>\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b163cb6 elementor-widget elementor-widget-ld_carousel\" data-id=\"1b163cb6\" data-element_type=\"widget\" data-widget_type=\"ld_carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div class=\"carousel-container pos-rel carousel-nav-left carousel-nav-left carousel-dots-mobile-outside carousel-dots-mobile-left yes\" id=\"\" >\n\n\t\t\t<div class=\"carousel-items pos-rel \"  data-lqd-flickity='{\"prevNextButtons\":true,\"groupCells\":true,\"navArrow\":\"6\",\"addSlideNumbersToArrows\":true,\"cellAlign\":\"left\",\"buttonsAppendTo\":\"self\",\"pageDots\":false}'>\n\n\t\t\t\t\t\t\t\t<div class=\"flickity-viewport pos-rel w-100 overflow-hidden\">\n\t\t\t\t\t<div class=\"flickity-slider d-flex w-100 h-100 pos-rel align-items-start\" style=\"left: 0; transform: translateX(0%);\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center elementor-repeater-item-9bb298b\">\n\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<span style=\"color: #ffffff; font-size: 25px; line-height: 39px;\">\u201cQuero deixar minha enorme satisfa\u00e7\u00e3o no resultado do meu tratamento com a Fisio D\u00e9bora Brand\u00e3o. Profissional altamente capacitada e qualificada. Al\u00e9m de atenciosa, sabe muito do que faz. Pontual e simp\u00e1tica. Super recomendo\u201d<\/span>\n<h6><span style=\"color: #ffffff; opacity: 0.5;\">Octavio Benatti<\/span><\/h6>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center elementor-repeater-item-9bb298b elementor-repeater-item-f6a6625\">\n\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<span style=\"color: #ffffff; font-size: 25px; line-height: 39px;\">\u201cEspa\u00e7o aconchegante. D\u00e9bora Brand\u00e3o, fisio, super profissional, atenciosa, dedicada...eu deveria ter conhecido antes, minha vida teria sido muito melhor!\u201d<\/span>\n<h6><span style=\"color: #ffffff; opacity: 0.5;\">Maria Terezinha Vilardo Lopes<\/span><\/h6>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center elementor-repeater-item-9bb298b elementor-repeater-item-f6a6625 elementor-repeater-item-3a55bea\">\n\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<span style=\"color: #ffffff; font-size: 25px; line-height: 39px;\">\u201cO que dizer da Dra Dalila?!\nProfissional super competente, dedicada, aten\u00e7\u00e3o especial para seu paciente .J\u00e1 tive necessidade de passar em tratamento de  reabilita\u00e7\u00e3o p\u00e9lvica com v\u00e1rios fisioterapeutas,  e sem d\u00favida posso afirmar que o trabalho da dra Dalila \u00e9  \u00edmpar, face todo seu conhecimento, bem como a sua pr\u00e1tica em nosso acompanhamento...\u201d<\/span>\n<h6><span style=\"color: #ffffff; opacity: 0.5;\"><\/span><\/h6>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-b4c2954 e-con-boxed e-con\" data-id=\"b4c2954\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4801941 elementor-widget elementor-widget-shortcode\" data-id=\"4801941\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\"><pre class=\"ti-widget\" style=\"display: none\"><template id=\"trustindex-google-widget-html\"><div class=\"ti-widget ti-goog ti-disable-font ti-show-rating-text ti-review-text-mode-readmore ti-content-align-left\" data-no-translation=\"true\" data-layout-id=\"4\" data-layout-category=\"slider\" data-set-id=\"light-background\" data-pid=\"\" data-language=\"pt\" data-review-target-width=\"300\" data-css-version=\"2\" data-review-text-mode=\"readmore\" data-reply-by-locale=\"Resposta do propriet\u00e1rio\" data-pager-autoplay-timeout=\"6\" > <div class=\"ti-widget-container ti-col-3\"> <div class=\"ti-reviews-container\"> <div class=\"ti-controls\"> <div class=\"ti-next\" aria-label=\"Pr\u00f3xima avalia\u00e7\u00e3o\" role=\"button\"><\/div> <div class=\"ti-prev\" aria-label=\"Avalia\u00e7\u00e3o anterior\" role=\"button\"><\/div> <\/div> <div class=\"ti-reviews-container-wrapper\">  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" > <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <trustindex-image class=\"ti-platform-icon\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\" ><\/trustindex-image> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocJzWgnvzgSVTFohQuQULMt_BC7KM7CATnCzTRBalxiQQZz4TQ=w64-h64-c-rp-mo-br100\" data-imgurlset=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocJzWgnvzgSVTFohQuQULMt_BC7KM7CATnCzTRBalxiQQZz4TQ=w128-h128-c-rp-mo-br100 2x\" alt=\"Edvan Duarte profile picture\" loading=\"lazy\" ><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Edvan Duarte <\/div> <div class=\"ti-date\">2025-04-07<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\" ><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\" ><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\" ><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\" ><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\" ><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica se a fonte original da avalia\u00e7\u00e3o \u00e9 Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Tudo perfeito.o paciente chega tenso e sai aliviado.atenfimento sem compara\u00e7\u00f5es.atendeu todas nossas expectativas.ja estou indicando aos amigos<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Esconder\" data-open-text=\"Consulte Mais informa\u00e7\u00e3o\" ><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" > <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <trustindex-image class=\"ti-platform-icon\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\" ><\/trustindex-image> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjWMMAn0m1hMoA8z3_qOY5VQpOfGaUmibAGsQbFlkpb8ZMLKmVY=w64-h64-c-rp-mo-br100\" data-imgurlset=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjWMMAn0m1hMoA8z3_qOY5VQpOfGaUmibAGsQbFlkpb8ZMLKmVY=w128-h128-c-rp-mo-br100 2x\" alt=\"Renata Ferraz profile picture\" loading=\"lazy\" ><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Renata Ferraz <\/div> <div class=\"ti-date\">2025-03-25<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\" ><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\" ><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\" ><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\" ><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\" ><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica se a fonte original da avalia\u00e7\u00e3o \u00e9 Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Foi fant\u00e1stica ! Super recomento !!!!! Ajudou muito<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Esconder\" data-open-text=\"Consulte Mais informa\u00e7\u00e3o\" ><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" > <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <trustindex-image class=\"ti-platform-icon\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\" ><\/trustindex-image> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocK4Pz-y4TmTWKNhPgaGIom-0EgDDANp63zJY12LaqdKuO4Rjw=w64-h64-c-rp-mo-br100\" data-imgurlset=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocK4Pz-y4TmTWKNhPgaGIom-0EgDDANp63zJY12LaqdKuO4Rjw=w128-h128-c-rp-mo-br100 2x\" alt=\"Cl\u00e1udia Anjos profile picture\" loading=\"lazy\" ><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Cl\u00e1udia Anjos <\/div> <div class=\"ti-date\">2025-03-07<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\" ><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\" ><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\" ><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\" ><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\" ><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica se a fonte original da avalia\u00e7\u00e3o \u00e9 Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Cheguei na Integra totalmente sem esperan\u00e7as e depois de 9 meses de tratamento com a Dalila sou outra pessoa, consigo evacuar normalmente. Espa\u00e7o de cuidado e respeito intenso. Eterna gratid\u00e3o!!!<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Esconder\" data-open-text=\"Consulte Mais informa\u00e7\u00e3o\" ><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" > <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <trustindex-image class=\"ti-platform-icon\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\" ><\/trustindex-image> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjVp2eZgNfmbi9QKVqJFYMR2dc8tgyRCzIZhhdv_xguhpbyvlbA=w64-h64-c-rp-mo-br100\" data-imgurlset=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjVp2eZgNfmbi9QKVqJFYMR2dc8tgyRCzIZhhdv_xguhpbyvlbA=w128-h128-c-rp-mo-br100 2x\" alt=\"Ariovaldo Antonio Augusto profile picture\" loading=\"lazy\" ><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Ariovaldo Antonio Augusto <\/div> <div class=\"ti-date\">2024-08-15<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\" ><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\" ><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\" ><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\" ><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\" ><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica se a fonte original da avalia\u00e7\u00e3o \u00e9 Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Fui meio receoso que poderia me recuperar, e a Dra Dalila com toda sua experi\u00eancia e capacidade, fez com que eu acreditasse em seu trabalho, e passo a passo, dia a dia,  fui me recuperando e estou bem agora , e praticamente livre da incontin\u00eancia urin\u00e1ria, ap\u00f3s a retirada da pr\u00f3stata , s\u00f3 tenho a agradecer pelo seu trabalho em me recuperar , e me fazer acreditar que era capaz de atingir o objetivo .<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Esconder\" data-open-text=\"Consulte Mais informa\u00e7\u00e3o\" ><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" > <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <trustindex-image class=\"ti-platform-icon\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\" ><\/trustindex-image> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocL8D9A00vpFoRZx9hxcNhnSGQHKHJcRTz3o0RTx4YYnK-RdHw=w64-h64-c-rp-mo-br100\" data-imgurlset=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocL8D9A00vpFoRZx9hxcNhnSGQHKHJcRTz3o0RTx4YYnK-RdHw=w128-h128-c-rp-mo-br100 2x\" alt=\"Nath\u00e1lia S. Medeiros Buarque profile picture\" loading=\"lazy\" ><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Nath\u00e1lia S. Medeiros Buarque <\/div> <div class=\"ti-date\">2024-07-31<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\" ><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\" ><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\" ><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\" ><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\" ><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica se a fonte original da avalia\u00e7\u00e3o \u00e9 Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Facilidade de comunica\u00e7\u00e3o e agendamento, profissionais competentes e ambiente acolhedor.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Esconder\" data-open-text=\"Consulte Mais informa\u00e7\u00e3o\" ><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" > <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <trustindex-image class=\"ti-platform-icon\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\" ><\/trustindex-image> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjVNFGV45EmFJWEhJyKoXniFDnPb00Vb6Cf8wGyi9ETPSzui-EL_=w64-h64-c-rp-mo-br100\" data-imgurlset=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjVNFGV45EmFJWEhJyKoXniFDnPb00Vb6Cf8wGyi9ETPSzui-EL_=w128-h128-c-rp-mo-br100 2x\" alt=\"Eliane Penhavel de Freitas profile picture\" loading=\"lazy\" ><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Eliane Penhavel de Freitas <\/div> <div class=\"ti-date\">2024-07-25<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\" ><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\" ><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\" ><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\" ><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\" ><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica se a fonte original da avalia\u00e7\u00e3o \u00e9 Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Na \u00cdntegra estive em atendimento com a profissional Dalila e super recomendo. Al\u00e9m do profissionalismo s\u00e9rio e competente, conversas boas que nos deixam mais confort\u00e1veis.\nEspero voltar ao atendimento assim que minha m\u00e9dica liberar p\u00f3s cirurgia.\nMuito obrigada por tudo!!<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Esconder\" data-open-text=\"Consulte Mais informa\u00e7\u00e3o\" ><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" > <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <trustindex-image class=\"ti-platform-icon\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\" ><\/trustindex-image> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocJrsSnA7yqDiJ__3c3sdLSHP2eSeLwISYmKkrsr32nb1IeWiw=w64-h64-c-rp-mo-br100\" data-imgurlset=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocJrsSnA7yqDiJ__3c3sdLSHP2eSeLwISYmKkrsr32nb1IeWiw=w128-h128-c-rp-mo-br100 2x\" alt=\"Luana Souza de Aguiar profile picture\" loading=\"lazy\" ><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Luana Souza de Aguiar <\/div> <div class=\"ti-date\">2024-07-22<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\" ><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\" ><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\" ><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\" ><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\" ><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica se a fonte original da avalia\u00e7\u00e3o \u00e9 Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Cl\u00ednica excelente e bem localizada. Dra Dalila \u00e9 uma profissional muito competente e atenciosa.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Esconder\" data-open-text=\"Consulte Mais informa\u00e7\u00e3o\" ><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" > <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <trustindex-image class=\"ti-platform-icon\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\" ><\/trustindex-image> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocKRG3TAG1AVPuH4_JgWXxn8NQRs5-vOdmD3y1GN95G3DFW-_g=w64-h64-c-rp-mo-br100\" data-imgurlset=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocKRG3TAG1AVPuH4_JgWXxn8NQRs5-vOdmD3y1GN95G3DFW-_g=w128-h128-c-rp-mo-br100 2x\" alt=\"Ayrton Stella profile picture\" loading=\"lazy\" ><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Ayrton Stella <\/div> <div class=\"ti-date\">2024-07-19<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\" ><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\" ><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\" ><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\" ><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\" ><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica se a fonte original da avalia\u00e7\u00e3o \u00e9 Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Excelente<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Esconder\" data-open-text=\"Consulte Mais informa\u00e7\u00e3o\" ><\/span> <\/div> <\/div>  <\/div> <div class=\"ti-controls-line\"> <div class=\"dot\"><\/div> <\/div> <\/div> <div class=\"ti-footer\"> <div class=\"ti-rating-text\"> <span class=\"nowrap\">Avalia\u00e7\u00e3o totalizada <strong>Google<\/strong> <\/span><span class=\"nowrap\"><strong>4.9<\/strong> de 5, <\/span><span class=\"nowrap\">com base em <strong>39 avalia\u00e7\u00f5es<\/strong><\/span> <\/div> <\/div>   <div class=\"ti-verified-by ti-verified-by-row\" data-style=\"1\"> <div class=\"ti-inner\"> Certificado: Trustindex <span class=\"ti-info-icon\"><\/span> <div class=\"ti-disclaimer\">O selo verificado do Trustindex \u00e9 o S\u00edmbolo Universal de Confian\u00e7a. Apenas as melhores empresas podem obter o selo verificado que tem uma pontua\u00e7\u00e3o de avalia\u00e7\u00e3o acima de 4.5, com base nas avalia\u00e7\u00f5es dos clientes nos \u00faltimos 12 meses. <a href=\"https:\/\/www.trustindex.io\/ti-redirect.php?a=sys&c=wp-verified-badge&url=\/the-trustindex-verified-badge\" target=\"_blank\">Leia mais<\/a><\/div> <\/div> <\/div>  <\/div> <\/div> <\/template><\/pre><div data-src=\"https:\/\/cdn.trustindex.io\/loader.js?wp-widget\" data-template-id=\"trustindex-google-widget-html\" data-css-url=\"https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/trustindex-google-widget.css?1747332613\"><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7352191 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7352191\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5118fd62\" data-id=\"5118fd62\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-53517ed0 elementor-widget__width-initial elementor-widget elementor-widget-ld_fancy_image\" data-id=\"53517ed0\" data-element_type=\"widget\" data-widget_type=\"ld_fancy_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t\t<div class=\"lqd-imggrp-single d-block pos-rel perspective\" data-shadow-style=\"3\" data-hover3d=\"true\"  >\n\t\t\t\t\n\t\t\t<div class=\"lqd-imggrp-img-container d-inline-flex pos-rel align-items-center justify-content-center transform-style-3d\">\n\t\t\t\t\t\t\t\t<figure class=\"w-100 pos-rel\" data-stacking-factor=\"1\"  >\n\t\t\t\t\t<img width=\"1024\" height=\"684\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 1024 684&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"Cl\u00ednica Integra SP\" decoding=\"async\" itemprop=\"image\" data-src=\"https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2022\/11\/PHOTO-2022-09-02-11-14-05.jpg\" data-srcset=\"https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2022\/11\/PHOTO-2022-09-02-11-14-05.jpg 1024w, https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2022\/11\/PHOTO-2022-09-02-11-14-05-300x200.jpg 300w, https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2022\/11\/PHOTO-2022-09-02-11-14-05-720x480.jpg 720w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" data-aspect=\"1.4970760233918\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3b8e7311\" data-id=\"3b8e7311\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dcc7530 elementor-widget__width-auto elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"dcc7530\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div id=\"ld-fancy-heading-69fc6d6f33e07\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<h6 class=\"ld-fh-element d-inline-block pos-rel  elementor-heading-title lqd-highlight-classic lqd-highlight-grow-left h6\"  > PARA VOC\u00ca SE SENTIR BEM!<\/h6>\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c024d3a elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"c024d3a\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div id=\"ld-fancy-heading-69fc6d6f35271\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<h2 class=\"ld-fh-element d-inline-block pos-rel  elementor-heading-title lqd-highlight-classic lqd-highlight-grow-left h2\"  > Conhe\u00e7a a cl\u00ednica<\/h2>\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66abda3f elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"66abda3f\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div id=\"ld-fancy-heading-69fc6d6f3670e\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<p class=\"ld-fh-element d-inline-block pos-rel  lqd-highlight-classic lqd-highlight-grow-left p\"  > Disponibilizamos dos equipamentos mais atualizados no mercado como biofeedback eletromiogr\u00e1fico e press\u00f3rico entre outros necess\u00e1rios para um tratamento de qualidade.\n<\/p>\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b5bb078 elementor-align-left elementor-widget elementor-widget-ld_icon_box\" data-id=\"b5bb078\" data-element_type=\"widget\" data-widget_type=\"ld_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t\t<div id=\"ld_icon_box_b5bb078\" class=\"iconbox d-flex flex-grow-1 pos-rel flex-wrap align-items-center iconbox-inline iconbox-icon-shaped iconbox-circle\"   >\n\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"iconbox-icon-wrap  \"><div class=\"iconbox-icon-container d-inline-flex pos-rel z-index-1 border-radius-circle\"><i aria-hidden=\"true\" class=\"lqd-icn-ess icon-ion-ios-checkmark\"><\/i><\/div><\/div>\t\t\t\t\n\t\t\t\t<h3 class=\"lqd-iconbox-heading \" >Biofeedback eletromiogr\u00e1fico\n <\/h3>\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<p><\/p>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69bfd942 elementor-align-left elementor-widget elementor-widget-ld_icon_box\" data-id=\"69bfd942\" data-element_type=\"widget\" data-widget_type=\"ld_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t\t<div id=\"ld_icon_box_69bfd942\" class=\"iconbox d-flex flex-grow-1 pos-rel flex-wrap align-items-center iconbox-inline iconbox-icon-shaped iconbox-circle\"   >\n\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"iconbox-icon-wrap  \"><div class=\"iconbox-icon-container d-inline-flex pos-rel z-index-1 border-radius-circle\"><i aria-hidden=\"true\" class=\"lqd-icn-ess icon-ion-ios-checkmark\"><\/i><\/div><\/div>\t\t\t\t\n\t\t\t\t<h3 class=\"lqd-iconbox-heading \" >Biofeedback press\u00f3rico\n <\/h3>\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<p><\/p>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77b408f5 elementor-align-left elementor-widget elementor-widget-ld_icon_box\" data-id=\"77b408f5\" data-element_type=\"widget\" data-widget_type=\"ld_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t\t<div id=\"ld_icon_box_77b408f5\" class=\"iconbox d-flex flex-grow-1 pos-rel flex-wrap align-items-center iconbox-inline iconbox-icon-shaped iconbox-circle\"   >\n\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"iconbox-icon-wrap  \"><div class=\"iconbox-icon-container d-inline-flex pos-rel z-index-1 border-radius-circle\"><i aria-hidden=\"true\" class=\"lqd-icn-ess icon-ion-ios-checkmark\"><\/i><\/div><\/div>\t\t\t\t\n\t\t\t\t<h3 class=\"lqd-iconbox-heading \" >Laserterapia <\/h3>\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<p><\/p>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dadc287 elementor-align-left elementor-widget elementor-widget-ld_icon_box\" data-id=\"dadc287\" data-element_type=\"widget\" data-widget_type=\"ld_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t\t<div id=\"ld_icon_box_dadc287\" class=\"iconbox d-flex flex-grow-1 pos-rel flex-wrap align-items-center iconbox-inline iconbox-icon-shaped iconbox-circle\"   >\n\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"iconbox-icon-wrap  \"><div class=\"iconbox-icon-container d-inline-flex pos-rel z-index-1 border-radius-circle\"><i aria-hidden=\"true\" class=\"lqd-icn-ess icon-ion-ios-checkmark\"><\/i><\/div><\/div>\t\t\t\t\n\t\t\t\t<h3 class=\"lqd-iconbox-heading \" >Eletroterapia <\/h3>\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<p><\/p>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8b56166 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8b56166\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8f56a8d\" data-id=\"8f56a8d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b843e17 elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"b843e17\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div id=\"ld-fancy-heading-69fc6d6f4d1c0\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<h2 class=\"ld-fh-element d-inline-block pos-rel  elementor-heading-title lqd-highlight-classic lqd-highlight-grow-left h2\"  > Dra. Dalila Duarte<\/h2>\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a1e38f elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"4a1e38f\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div id=\"ld-fancy-heading-69fc6d6f4ee18\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<p class=\"ld-fh-element d-inline-block pos-rel  lqd-highlight-classic lqd-highlight-grow-left p\"  > Fisioterapeuta formada pela PUC-SP, p\u00f3s graduada em Sa\u00fade da Mulher e do Homem pela Santa Casa de S\u00e3o Paulo, Respons\u00e1vel pela equipe de Fisioterapia P\u00e9lvica no Hospital Alem\u00e3o Oswaldo Cruz, Pesquisadora colaboradora no grupo de Motilidade Digestiva do HC-FMUSP e professora convidada de diversas p\u00f3s-gradua\u00e7\u00f5es.\n<\/p>\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-725d3f0\" data-id=\"725d3f0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6bdab8a elementor-widget elementor-widget-menu-anchor\" data-id=\"6bdab8a\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"equipe\" class=\"elementor-menu-anchor\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-83a57f3 elementor-widget__width-initial elementor-widget elementor-widget-ld_fancy_image\" data-id=\"83a57f3\" data-element_type=\"widget\" data-widget_type=\"ld_fancy_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t\t<div class=\"lqd-imggrp-single d-block pos-rel perspective\" data-shadow-style=\"3\" data-hover3d=\"true\"  >\n\t\t\t\t\n\t\t\t<div class=\"lqd-imggrp-img-container d-inline-flex pos-rel align-items-center justify-content-center transform-style-3d\">\n\t\t\t\t\t\t\t\t<figure class=\"w-100 pos-rel\" data-stacking-factor=\"1\"  >\n\t\t\t\t\t<img width=\"768\" height=\"1151\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 1068 1600&#039;%2F%3E\" class=\"attachment-medium_large size-medium_large ld-lazyload\" alt=\"Cl\u00ednica Integra SP\" decoding=\"async\" itemprop=\"image\" data-src=\"https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2022\/11\/PHOTO-2022-09-01-21-27-05.jpg\" data-srcset=\"https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2022\/11\/PHOTO-2022-09-01-21-27-05.jpg 1068w, https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2022\/11\/PHOTO-2022-09-01-21-27-05-200x300.jpg 200w, https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2022\/11\/PHOTO-2022-09-01-21-27-05-684x1024.jpg 684w, https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2022\/11\/PHOTO-2022-09-01-21-27-05-1025x1536.jpg 1025w\" data-sizes=\"(max-width: 768px) 100vw, 768px\" data-aspect=\"0.6675\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-48d4ee0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"48d4ee0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-800b505\" data-id=\"800b505\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-deec603 elementor-widget__width-initial elementor-widget elementor-widget-ld_fancy_image\" data-id=\"deec603\" data-element_type=\"widget\" data-widget_type=\"ld_fancy_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t\t<div class=\"lqd-imggrp-single d-block pos-rel perspective\" data-shadow-style=\"3\" data-hover3d=\"true\"  >\n\t\t\t\t\n\t\t\t<div class=\"lqd-imggrp-img-container d-inline-flex pos-rel align-items-center justify-content-center transform-style-3d\">\n\t\t\t\t\t\t\t\t<figure class=\"w-100 pos-rel\" data-stacking-factor=\"1\"  >\n\t\t\t\t\t<img width=\"513\" height=\"768\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 513 768&#039;%2F%3E\" class=\"attachment-medium_large size-medium_large ld-lazyload\" alt=\"Cl\u00ednica Integra SP\" decoding=\"async\" itemprop=\"image\" data-src=\"https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2022\/11\/PHOTO-2022-09-01-21-23-00.jpg\" data-srcset=\"https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2022\/11\/PHOTO-2022-09-01-21-23-00.jpg 513w, https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2022\/11\/PHOTO-2022-09-01-21-23-00-200x300.jpg 200w\" data-sizes=\"(max-width: 513px) 100vw, 513px\" data-aspect=\"0.66796875\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-789eb92\" data-id=\"789eb92\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-edc969b elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"edc969b\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div id=\"ld-fancy-heading-69fc6d6f76829\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<h2 class=\"ld-fh-element d-inline-block pos-rel  elementor-heading-title lqd-highlight-classic lqd-highlight-grow-left h2\"  > Dra. D\u00e9bora Brand\u00e3o\n<\/h2>\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-419ec9a elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"419ec9a\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div id=\"ld-fancy-heading-69fc6d6f77bcb\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<p class=\"ld-fh-element d-inline-block pos-rel  lqd-highlight-classic lqd-highlight-grow-left p\"  > Fisioterapeuta formada pela PUC-SP, com especializa\u00e7\u00e3o em Sa\u00fade da Mulher pelo ICHC-FMUSP e Mestranda pelo Departamento de Gastroenterologia pelo ICHC-FMUSP.\n<br><Br>\nProfessora convidada em p\u00f3s gradua\u00e7\u00f5es de sa\u00fade p\u00e9lvica.\n<\/p>\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2e8365a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2e8365a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-74e6ae7\" data-id=\"74e6ae7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-14f4322 elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"14f4322\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div id=\"ld-fancy-heading-69fc6d6f7a82a\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<h2 class=\"ld-fh-element d-inline-block pos-rel  elementor-heading-title lqd-highlight-classic lqd-highlight-grow-left h2\"  > Dra. Silvia Noffs<\/h2>\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b749c9a elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"b749c9a\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div id=\"ld-fancy-heading-69fc6d6f7bd29\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<p class=\"ld-fh-element d-inline-block pos-rel  lqd-highlight-classic lqd-highlight-grow-left p\"  > - Fisioterapeuta pela PUC-SP\n- Especializada em Sa\u00fade P\u00e9lvica pelo HC-FMUSP\n- Fisioterapeuta nos ambulat\u00f3rios de Disfun\u00e7\u00e3o miccional e Andrologia na UNIFESP-EPM\n- Mestrado em andamento no PPG de Urologia na UNIFESP-EPM\n<\/p>\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f76a220\" data-id=\"f76a220\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-28985dd elementor-widget elementor-widget-menu-anchor\" data-id=\"28985dd\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"equipe\" class=\"elementor-menu-anchor\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bc6276c elementor-widget__width-initial elementor-widget elementor-widget-ld_fancy_image\" data-id=\"bc6276c\" data-element_type=\"widget\" data-widget_type=\"ld_fancy_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t\t<div class=\"lqd-imggrp-single d-block pos-rel perspective\" data-shadow-style=\"3\" data-hover3d=\"true\"  >\n\t\t\t\t\n\t\t\t<div class=\"lqd-imggrp-img-container d-inline-flex pos-rel align-items-center justify-content-center transform-style-3d\">\n\t\t\t\t\t\t\t\t<figure class=\"w-100 pos-rel\" data-stacking-factor=\"1\"  >\n\t\t\t\t\t<img width=\"768\" height=\"1153\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 1066 1600&#039;%2F%3E\" class=\"attachment-medium_large size-medium_large ld-lazyload\" alt=\"\" decoding=\"async\" itemprop=\"image\" data-src=\"https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-14-at-12.05.38.png\" data-srcset=\"https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-14-at-12.05.38.png 1066w, https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-14-at-12.05.38-200x300.png 200w, https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-14-at-12.05.38-682x1024.png 682w, https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-14-at-12.05.38-1023x1536.png 1023w\" data-sizes=\"(max-width: 768px) 100vw, 768px\" data-aspect=\"0.66625\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7ffbe04 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7ffbe04\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e81966b\" data-id=\"e81966b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-903b960 elementor-widget__width-initial elementor-widget elementor-widget-ld_fancy_image\" data-id=\"903b960\" data-element_type=\"widget\" data-widget_type=\"ld_fancy_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t\t<div class=\"lqd-imggrp-single d-block pos-rel perspective\" data-shadow-style=\"3\" data-hover3d=\"true\"  >\n\t\t\t\t\n\t\t\t<div class=\"lqd-imggrp-img-container d-inline-flex pos-rel align-items-center justify-content-center transform-style-3d\">\n\t\t\t\t\t\t\t\t<figure class=\"w-100 pos-rel\" data-stacking-factor=\"1\"  >\n\t\t\t\t\t<img width=\"768\" height=\"1168\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 789 1200&#039;%2F%3E\" class=\"attachment-medium_large size-medium_large ld-lazyload\" alt=\"\" decoding=\"async\" itemprop=\"image\" data-src=\"https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2025\/05\/fisio-integra.png\" data-srcset=\"https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2025\/05\/fisio-integra.png 789w, https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2025\/05\/fisio-integra-197x300.png 197w, https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2025\/05\/fisio-integra-673x1024.png 673w\" data-sizes=\"(max-width: 768px) 100vw, 768px\" data-aspect=\"0.6575\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-140aa8d\" data-id=\"140aa8d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-91f6642 elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"91f6642\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div id=\"ld-fancy-heading-69fc6d6fa4c1e\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<h2 class=\"ld-fh-element d-inline-block pos-rel  elementor-heading-title lqd-highlight-classic lqd-highlight-grow-left h2\"  > Dra. B\u00e1rbara Fortunato\n<\/h2>\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b6a7b46 elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"b6a7b46\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div id=\"ld-fancy-heading-69fc6d6fa6ac8\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<p class=\"ld-fh-element d-inline-block pos-rel  lqd-highlight-classic lqd-highlight-grow-left p\"  > - Fisioterapeuta pela PUC-SP\n- Especializada em Sa\u00fade P\u00e9lvica pelo HC-FMUSP\n- Fisioterapeuta e pesquisadora no ambulat\u00f3rio de Gestantes, Pu\u00e9rperas e Assoalho P\u00e9lvico na UNIFESP-EPM\n- Fisioterapeuta do Centro Obst\u00e9trico do Hospital SEPACO \n- Preceptora do curso \u201cDa gesta\u00e7\u00e3o at\u00e9 a sala de parto\u201d na Maternidade de Interlagos.\n<\/p>\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cc6667c elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"cc6667c\" data-element_type=\"section\" id=\"about\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_top&quot;:&quot;waves&quot;,&quot;shape_divider_bottom&quot;:&quot;waves&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M421.9,6.5c22.6-2.5,51.5,0.4,75.5,5.3c23.6,4.9,70.9,23.5,100.5,35.7c75.8,32.2,133.7,44.5,192.6,49.7\n\tc23.6,2.1,48.7,3.5,103.4-2.5c54.7-6,106.2-25.6,106.2-25.6V0H0v30.3c0,0,72,32.6,158.4,30.5c39.2-0.7,92.8-6.7,134-22.4\n\tc21.2-8.1,52.2-18.2,79.7-24.2C399.3,7.9,411.6,7.5,421.9,6.5z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M421.9,6.5c22.6-2.5,51.5,0.4,75.5,5.3c23.6,4.9,70.9,23.5,100.5,35.7c75.8,32.2,133.7,44.5,192.6,49.7\n\tc23.6,2.1,48.7,3.5,103.4-2.5c54.7-6,106.2-25.6,106.2-25.6V0H0v30.3c0,0,72,32.6,158.4,30.5c39.2-0.7,92.8-6.7,134-22.4\n\tc21.2-8.1,52.2-18.2,79.7-24.2C399.3,7.9,411.6,7.5,421.9,6.5z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9f37822\" data-id=\"9f37822\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4bf5f112 elementor-widget__width-initial elementor-absolute elementor-widget elementor-widget-ld_fancy_image\" data-id=\"4bf5f112\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"ld_fancy_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t\t<div class=\"lqd-imggrp-single d-block pos-rel\" data-shadow-style=\"4\" data-inview=\"true\" data-animate-shadow=\"true\"  >\n\t\t\t\t\n\t\t\t<div class=\"lqd-imggrp-img-container d-inline-flex pos-rel align-items-center justify-content-center\">\n\t\t\t\t\t\t\t\t<figure class=\"w-100 pos-rel\"   >\n\t\t\t\t\t<img width=\"1150\" height=\"768\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 1150 768&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" decoding=\"async\" itemprop=\"image\" data-src=\"https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2022\/11\/PHOTO-2022-09-02-11-11-08.jpg\" data-srcset=\"https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2022\/11\/PHOTO-2022-09-02-11-11-08.jpg 1150w, https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2022\/11\/PHOTO-2022-09-02-11-11-08-300x200.jpg 300w, https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2022\/11\/PHOTO-2022-09-02-11-11-08-1024x684.jpg 1024w, https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2022\/11\/PHOTO-2022-09-02-11-11-08-720x480.jpg 720w\" data-sizes=\"(max-width: 1150px) 100vw, 1150px\" data-aspect=\"1.4973958333333\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e57a891 elementor-widget__width-initial elementor-widget elementor-widget-ld_fancy_image\" data-id=\"5e57a891\" data-element_type=\"widget\" data-widget_type=\"ld_fancy_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t\t<div class=\"lqd-imggrp-single d-block pos-rel\" data-shadow-style=\"4\" data-inview=\"true\" data-inview-options='{\"delayTime\":250}' data-animate-shadow=\"true\"  >\n\t\t\t\t\n\t\t\t<div class=\"lqd-imggrp-img-container d-inline-flex pos-rel align-items-center justify-content-center\">\n\t\t\t\t\t\t\t\t<figure class=\"w-100 pos-rel\"   >\n\t\t\t\t\t<img width=\"3923\" height=\"5876\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 3923 5876&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"Cl\u00ednica Integra SP\" decoding=\"async\" itemprop=\"image\" data-src=\"https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2022\/11\/dalila_siteee.jpg\" data-srcset=\"https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2022\/11\/dalila_siteee.jpg 3923w, https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2022\/11\/dalila_siteee-200x300.jpg 200w, https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2022\/11\/dalila_siteee-684x1024.jpg 684w, https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2022\/11\/dalila_siteee-1367x2048.jpg 1367w, https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2022\/11\/dalila_siteee-1025x1536.jpg 1025w\" data-sizes=\"(max-width: 3923px) 100vw, 3923px\" data-aspect=\"0.66763104152485\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3626c7d7 elementor-widget__width-initial elementor-absolute elementor-widget-mobile__width-initial elementor-widget elementor-widget-ld_fancy_image\" data-id=\"3626c7d7\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"ld_fancy_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t\t<div class=\"lqd-imggrp-single d-block pos-rel\" data-shadow-style=\"4\" data-inview=\"true\" data-inview-options='{\"delayTime\":500}' data-animate-shadow=\"true\"  >\n\t\t\t\t\n\t\t\t<div class=\"lqd-imggrp-img-container d-inline-flex pos-rel align-items-center justify-content-center\">\n\t\t\t\t\t\t\t\t<figure class=\"w-100 pos-rel\"   >\n\t\t\t\t\t<img width=\"1024\" height=\"684\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 1024 684&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"Cl\u00ednica Integra SP\" decoding=\"async\" itemprop=\"image\" data-src=\"https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2022\/11\/PHOTO-2022-09-02-11-14-05.jpg\" data-srcset=\"https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2022\/11\/PHOTO-2022-09-02-11-14-05.jpg 1024w, https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2022\/11\/PHOTO-2022-09-02-11-14-05-300x200.jpg 300w, https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2022\/11\/PHOTO-2022-09-02-11-14-05-720x480.jpg 720w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" data-aspect=\"1.4970760233918\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4f196652\" data-id=\"4f196652\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-617cfff elementor-widget__width-auto elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"617cfff\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div id=\"ld-fancy-heading-69fc6d6fe386c\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<h6 class=\"ld-fh-element d-inline-block pos-rel  elementor-heading-title lqd-highlight-classic lqd-highlight-grow-left h6\"  > Conhe\u00e7a os nossos tratamentos<\/h6>\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d06c1d elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"6d06c1d\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div id=\"ld-fancy-heading-69fc6d6fe521c\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<h2 class=\"ld-fh-element d-inline-block pos-rel  elementor-heading-title lqd-highlight-classic lqd-highlight-grow-left h2\"  > Massoterapia Integrativa\n<br>\nNutri\u00e7\u00e3o<\/h2>\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b6efa44 elementor-widget elementor-widget-ld_accordion\" data-id=\"5b6efa44\" data-element_type=\"widget\" data-widget_type=\"ld_accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div class=\"accordion accordion-title-underlined accordion-lg\" id=\"accordion-69fc6d6fe794c\" role=\"tablist\" aria-multiselectable=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"accordion-item panel \">\n\t\t\t\t\n\t\t\t\t<div class=\"accordion-heading\" role=\"tab\" id=\"heading-1531\">\n\t\t\t\t<h4 class=\"accordion-title \">\t\t\t\t\t<a class=\"collapsed\" role=\"button\" data-toggle=\"collapse\" \n\t\t\t\t\tdata-parent=\"#accordion-69fc6d6fe794c\" href=\"#collapse-1531\" \n\t\t\t\t\taria-expanded=\"false\" aria-controls=\"collapse-1531\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-title-txt\">Massagem<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-expander\"><i class=\"lqd-icn-ess icon-ion-ios-add\"><\/i><i class=\"lqd-icn-ess icon-ion-ios-remove\"><\/i><\/span>\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div id=\"collapse-1531\" class=\"accordion-collapse collapse \" role=\"tabpanel\" aria-labelledby=\"heading-1531\">\n\n\t\t\t\t<div class=\"accordion-content\">\n\t\t\t\t\tA massoterapia disponibiliza tempo para voc\u00ea cuidar do seu bem-estar e manter o equil\u00edbrio.\n<br><br>\nA massagem trabalha com canais energ\u00e9ticos do seu corpo, ou seja, com alinhamento. S\u00e3o estimuladas algumas regi\u00f5es do corpo caso a energia esteja baixa ou quando necess\u00e1rio, promovendo o relaxamento, buscando maior fluxo da circula\u00e7\u00e3o e sensa\u00e7\u00e3o de paz interior.\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"accordion-item panel \">\n\t\t\t\t\n\t\t\t\t<div class=\"accordion-heading\" role=\"tab\" id=\"heading-1532\">\n\t\t\t\t<h4 class=\"accordion-title \">\t\t\t\t\t<a class=\"collapsed\" role=\"button\" data-toggle=\"collapse\" \n\t\t\t\t\tdata-parent=\"#accordion-69fc6d6fe794c\" href=\"#collapse-1532\" \n\t\t\t\t\taria-expanded=\"false\" aria-controls=\"collapse-1532\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-title-txt\">Nutri\u00e7\u00e3o<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-expander\"><i class=\"lqd-icn-ess icon-ion-ios-add\"><\/i><i class=\"lqd-icn-ess icon-ion-ios-remove\"><\/i><\/span>\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div id=\"collapse-1532\" class=\"accordion-collapse collapse \" role=\"tabpanel\" aria-labelledby=\"heading-1532\">\n\n\t\t\t\t<div class=\"accordion-content\">\n\t\t\t\t\t*Nutri\u00e7\u00e3o com foco em comportamento.*\n<br><Br>\n\nO atendimento nutricional com foco em comportamento, \u00e9 uma abordagem sem dietas restritivas, que traz in\u00fameros benef\u00edcios para quem precisa: prevenir ou tratar doen\u00e7as cr\u00f4nicas, melhorar a qualidade de vida e para aqueles que buscam por longevidade.\n<br><Br>\nAtrav\u00e9s da alimenta\u00e7\u00e3o equilibrada e sem neuras, \u00e9 poss\u00edvel melhorar sua rela\u00e7\u00e3o com seu corpo e com a comida!\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-267eeb93 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"267eeb93\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_top&quot;:&quot;opacity-tilt&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 2600 131.1\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0 0L2600 0 2600 69.1 0 0z\"\/>\n\t<path class=\"elementor-shape-fill\" style=\"opacity:0.5\" d=\"M0 0L2600 0 2600 69.1 0 69.1z\"\/>\n\t<path class=\"elementor-shape-fill\" style=\"opacity:0.25\" d=\"M2600 0L0 0 0 130.1 2600 69.1z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-69847645\" data-id=\"69847645\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-220b769e elementor-widget elementor-widget-ld_fancy_image\" data-id=\"220b769e\" data-element_type=\"widget\" data-widget_type=\"ld_fancy_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t\t<div class=\"lqd-imggrp-single d-block pos-rel\"   >\n\t\t\t\t\n\t\t\t<div class=\"lqd-imggrp-img-container d-inline-flex pos-rel align-items-center justify-content-center\">\n\t\t\t\t\t\t\t\t<figure class=\"w-100 pos-rel\"   >\n\t\t\t\t\t<img width=\"2475\" height=\"864\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2475 864&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" decoding=\"async\" itemprop=\"image\" data-src=\"https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2022\/11\/Integra_Saude_PNG.png\" data-srcset=\"https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2022\/11\/Integra_Saude_PNG.png 2475w, https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2022\/11\/Integra_Saude_PNG-300x105.png 300w, https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2022\/11\/Integra_Saude_PNG-1024x357.png 1024w, https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2022\/11\/Integra_Saude_PNG-1536x536.png 1536w, https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/2022\/11\/Integra_Saude_PNG-2048x715.png 2048w\" data-sizes=\"(max-width: 2475px) 100vw, 2475px\" data-aspect=\"2.8645833333333\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-109cdeb6 elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"109cdeb6\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div id=\"ld-fancy-heading-69fc6d7006aa3\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<p class=\"ld-fh-element d-inline-block pos-rel  lqd-highlight-classic lqd-highlight-grow-left p\"  > Fisioterapia P\u00e9lvica ( Homens e Mulheres \/ Obstetricia\/ Urologia \/ Sexualidade e Coloproctologia)<\/p>\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67e86e77 e-grid-align-left e-grid-align-tablet-left elementor-shape-rounded elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"67e86e77\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.8.1 - 13-11-2022 *\/\n.elementor-widget-social-icons.elementor-grid-0 .elementor-widget-container,.elementor-widget-social-icons.elementor-grid-mobile-0 .elementor-widget-container,.elementor-widget-social-icons.elementor-grid-tablet-0 .elementor-widget-container{line-height:1;font-size:0}.elementor-widget-social-icons:not(.elementor-grid-0):not(.elementor-grid-tablet-0):not(.elementor-grid-mobile-0) .elementor-grid{display:inline-grid}.elementor-widget-social-icons .elementor-grid{grid-column-gap:var(--grid-column-gap,5px);grid-row-gap:var(--grid-row-gap,5px);grid-template-columns:var(--grid-template-columns);-webkit-box-pack:var(--justify-content,center);-ms-flex-pack:var(--justify-content,center);justify-content:var(--justify-content,center);justify-items:var(--justify-content,center)}.elementor-icon.elementor-social-icon{font-size:var(--icon-size,25px);line-height:var(--icon-size,25px);width:calc(var(--icon-size, 25px) + (2 * var(--icon-padding, .5em)));height:calc(var(--icon-size, 25px) + (2 * var(--icon-padding, .5em)))}.elementor-social-icon{--e-social-icon-icon-color:#fff;display:-webkit-inline-box;display:-ms-inline-flexbox;display:inline-flex;background-color:#818a91;-webkit-box-align:center;-ms-flex-align:center;align-items:center;-webkit-box-pack:center;-ms-flex-pack:center;justify-content:center;text-align:center;cursor:pointer}.elementor-social-icon i{color:var(--e-social-icon-icon-color)}.elementor-social-icon svg{fill:var(--e-social-icon-icon-color)}.elementor-social-icon:last-child{margin:0}.elementor-social-icon:hover{opacity:.9;color:#fff}.elementor-social-icon-android{background-color:#a4c639}.elementor-social-icon-apple{background-color:#999}.elementor-social-icon-behance{background-color:#1769ff}.elementor-social-icon-bitbucket{background-color:#205081}.elementor-social-icon-codepen{background-color:#000}.elementor-social-icon-delicious{background-color:#39f}.elementor-social-icon-deviantart{background-color:#05cc47}.elementor-social-icon-digg{background-color:#005be2}.elementor-social-icon-dribbble{background-color:#ea4c89}.elementor-social-icon-elementor{background-color:#d30c5c}.elementor-social-icon-envelope{background-color:#ea4335}.elementor-social-icon-facebook,.elementor-social-icon-facebook-f{background-color:#3b5998}.elementor-social-icon-flickr{background-color:#0063dc}.elementor-social-icon-foursquare{background-color:#2d5be3}.elementor-social-icon-free-code-camp,.elementor-social-icon-freecodecamp{background-color:#006400}.elementor-social-icon-github{background-color:#333}.elementor-social-icon-gitlab{background-color:#e24329}.elementor-social-icon-globe{background-color:#818a91}.elementor-social-icon-google-plus,.elementor-social-icon-google-plus-g{background-color:#dd4b39}.elementor-social-icon-houzz{background-color:#7ac142}.elementor-social-icon-instagram{background-color:#262626}.elementor-social-icon-jsfiddle{background-color:#487aa2}.elementor-social-icon-link{background-color:#818a91}.elementor-social-icon-linkedin,.elementor-social-icon-linkedin-in{background-color:#0077b5}.elementor-social-icon-medium{background-color:#00ab6b}.elementor-social-icon-meetup{background-color:#ec1c40}.elementor-social-icon-mixcloud{background-color:#273a4b}.elementor-social-icon-odnoklassniki{background-color:#f4731c}.elementor-social-icon-pinterest{background-color:#bd081c}.elementor-social-icon-product-hunt{background-color:#da552f}.elementor-social-icon-reddit{background-color:#ff4500}.elementor-social-icon-rss{background-color:#f26522}.elementor-social-icon-shopping-cart{background-color:#4caf50}.elementor-social-icon-skype{background-color:#00aff0}.elementor-social-icon-slideshare{background-color:#0077b5}.elementor-social-icon-snapchat{background-color:#fffc00}.elementor-social-icon-soundcloud{background-color:#f80}.elementor-social-icon-spotify{background-color:#2ebd59}.elementor-social-icon-stack-overflow{background-color:#fe7a15}.elementor-social-icon-steam{background-color:#00adee}.elementor-social-icon-stumbleupon{background-color:#eb4924}.elementor-social-icon-telegram{background-color:#2ca5e0}.elementor-social-icon-thumb-tack{background-color:#1aa1d8}.elementor-social-icon-tripadvisor{background-color:#589442}.elementor-social-icon-tumblr{background-color:#35465c}.elementor-social-icon-twitch{background-color:#6441a5}.elementor-social-icon-twitter{background-color:#1da1f2}.elementor-social-icon-viber{background-color:#665cac}.elementor-social-icon-vimeo{background-color:#1ab7ea}.elementor-social-icon-vk{background-color:#45668e}.elementor-social-icon-weibo{background-color:#dd2430}.elementor-social-icon-weixin{background-color:#31a918}.elementor-social-icon-whatsapp{background-color:#25d366}.elementor-social-icon-wordpress{background-color:#21759b}.elementor-social-icon-xing{background-color:#026466}.elementor-social-icon-yelp{background-color:#af0606}.elementor-social-icon-youtube{background-color:#cd201f}.elementor-social-icon-500px{background-color:#0099e5}.elementor-shape-rounded .elementor-icon.elementor-social-icon{border-radius:10%}.elementor-shape-circle .elementor-icon.elementor-social-icon{border-radius:50%}<\/style>\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-0f79c7f\" href=\"https:\/\/www.instagram.com\/integra.saudesp\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-whatsapp elementor-repeater-item-f967265\" href=\"https:\/\/wa.link\/mryzpa\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Whatsapp<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-whatsapp\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-59613cba elementor-hidden-mobile\" data-id=\"59613cba\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-10bb2228\" data-id=\"10bb2228\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e7508dd elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"6e7508dd\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div id=\"ld-fancy-heading-69fc6d7009ddd\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<h3 class=\"ld-fh-element d-inline-block pos-rel  elementor-heading-title lqd-highlight-classic lqd-highlight-grow-left h3\"  > Contato<\/h3>\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-de90e61 elementor-align-left elementor-widget elementor-widget-ld_icon_box\" data-id=\"de90e61\" data-element_type=\"widget\" data-widget_type=\"ld_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t\t<div id=\"ld_icon_box_de90e61\" class=\"iconbox d-flex flex-grow-1 pos-rel flex-wrap align-items-center iconbox-inline\"   >\n\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"iconbox-icon-wrap  \"><div class=\"iconbox-icon-container d-inline-flex   \"><i aria-hidden=\"true\" class=\"fas fa-map-marker-alt\"><\/i><\/div><\/div>\t\t\t\t\n\t\t\t\t<h3 class=\"lqd-iconbox-heading \" >Rua Dr. Tirso Martins, 100, Cj 503, Vila Mariana \/ SP <\/h3>\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<p><\/p>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8835dfb elementor-align-left elementor-widget elementor-widget-ld_icon_box\" data-id=\"8835dfb\" data-element_type=\"widget\" data-widget_type=\"ld_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t\t<div id=\"ld_icon_box_8835dfb\" class=\"iconbox d-flex flex-grow-1 pos-rel flex-wrap align-items-center iconbox-inline\"   >\n\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"iconbox-icon-wrap  \"><div class=\"iconbox-icon-container d-inline-flex   \"><i aria-hidden=\"true\" class=\"fas fa-map-marker-alt\"><\/i><\/div><\/div>\t\t\t\t\n\t\t\t\t<h3 class=\"lqd-iconbox-heading \" >Av. Cauaxi, 293 - sala 110 - Alphaville Industrial\/SP <\/h3>\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<p><\/p>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-303b235 elementor-align-left elementor-widget elementor-widget-ld_icon_box\" data-id=\"303b235\" data-element_type=\"widget\" data-widget_type=\"ld_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t\t<div id=\"ld_icon_box_303b235\" class=\"iconbox d-flex flex-grow-1 pos-rel flex-wrap align-items-center iconbox-inline\"   >\n\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"iconbox-icon-wrap  \"><div class=\"iconbox-icon-container d-inline-flex   \"><i aria-hidden=\"true\" class=\"fas fa-envelope\"><\/i><\/div><\/div>\t\t\t\t\n\t\t\t\t<h3 class=\"lqd-iconbox-heading \" >sp.integrasaude@gmail.com <\/h3>\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<p><\/p>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e45dda3 elementor-align-left elementor-widget elementor-widget-ld_icon_box\" data-id=\"e45dda3\" data-element_type=\"widget\" data-widget_type=\"ld_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t\t<div id=\"ld_icon_box_e45dda3\" class=\"iconbox d-flex flex-grow-1 pos-rel flex-wrap align-items-center iconbox-inline\"   >\n\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"iconbox-icon-wrap  \"><div class=\"iconbox-icon-container d-inline-flex   \"><i aria-hidden=\"true\" class=\"fas fa-mobile\"><\/i><\/div><\/div>\t\t\t\t\n\t\t\t\t<h3 class=\"lqd-iconbox-heading \" >(11) 99853-7408\n <\/h3>\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<p><\/p>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-4fca30ce\" data-id=\"4fca30ce\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56d13cc4 elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"56d13cc4\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div id=\"ld-fancy-heading-69fc6d7024428\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<h3 class=\"ld-fh-element d-inline-block pos-rel  elementor-heading-title lqd-highlight-classic lqd-highlight-grow-left h3\"  > Avalia-nos no Google!<br>\nAguardamos o seu feedback<\/h3>\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3af798bb elementor-align-justify elementor-tablet-align-justify elementor-widget elementor-widget-ld_button\" data-id=\"3af798bb\" data-element_type=\"widget\" data-widget_type=\"ld_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<a  href=\"https:\/\/g.page\/r\/CRD1CK3MMYOvEBM\/review\" class=\"elementor-button btn ws-nowrap btn-solid btn-icon-left btn-has-label\" >\n\t\t\t\t\t\t\t<span class=\"btn-txt\"  data-text=\"NOS AVALIE NO GOOGLE\" >NOS AVALIE NO GOOGLE<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"btn-icon\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-handshake\"><\/i>\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb2e395 elementor-align-justify elementor-tablet-align-justify elementor-widget elementor-widget-ld_button\" data-id=\"bb2e395\" data-element_type=\"widget\" data-widget_type=\"ld_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<a  href=\"https:\/\/g.page\/r\/CcUuotkUgPCMEBM\/review\" class=\"elementor-button btn ws-nowrap btn-solid btn-icon-left btn-has-label\" >\n\t\t\t\t\t\t\t<span class=\"btn-txt\"  data-text=\"NOS AVALIE NO GOOGLE\" >NOS AVALIE NO GOOGLE<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"btn-icon\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-handshake\"><\/i>\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59bb8a2e elementor-icon-list--layout-inline elementor-align-center elementor-widget__width-auto elementor-mobile-align-center elementor-widget-mobile__width-inherit elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"59bb8a2e\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/spintegrasaude.com.br\/wp-content\/uploads\/elementor\/css\/custom-widget-icon-list.min.css?ver=1747334755\">\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-star\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-star\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-star\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-star\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-star\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5763d218 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5763d218\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-52dd2339\" data-id=\"52dd2339\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-461751a5 elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"461751a5\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div id=\"ld-fancy-heading-69fc6d703565e\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<p class=\"ld-fh-element d-inline-block pos-rel  lqd-highlight-classic lqd-highlight-grow-left p\"  > \u00a9 Cl\u00ednica Integra 2022. Todos os direitos reservados. Produzido por <a href=\"https:\/\/kemotion.com.br\/\" style=\"font-family: Rubik, sans-serif\">Kemotion Lab<\/a><\/p>\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Recupere sua confian\u00e7a e bem-estar! Agende uma avalia\u00e7\u00e3o hoje e d\u00ea o primeiro passo para uma vida sem desconforto e limita\u00e7\u00f5es. Agende J\u00e1 pelo Whatsapp! ou ligue para (11) 99853-7408 Somos especializados em Fisioterapia P\u00e9lvica. Nossa cl\u00ednica est\u00e1 localizada na Vila Mariana em S\u00e3o Paulo, atendemos Homens e Mulheres Obstetr\u00edcia Nesta \u00e1rea auxiliamos uma gesta\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_joinchat":[]},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/spintegrasaude.com.br\/index.php\/wp-json\/wp\/v2\/pages\/12724"}],"collection":[{"href":"https:\/\/spintegrasaude.com.br\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/spintegrasaude.com.br\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/spintegrasaude.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/spintegrasaude.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=12724"}],"version-history":[{"count":216,"href":"https:\/\/spintegrasaude.com.br\/index.php\/wp-json\/wp\/v2\/pages\/12724\/revisions"}],"predecessor-version":[{"id":13498,"href":"https:\/\/spintegrasaude.com.br\/index.php\/wp-json\/wp\/v2\/pages\/12724\/revisions\/13498"}],"wp:attachment":[{"href":"https:\/\/spintegrasaude.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=12724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}